{"id":25375,"date":"2023-09-28T12:07:24","date_gmt":"2023-09-28T12:07:24","guid":{"rendered":"https:\/\/topliefer.com\/?page_id=25375"},"modified":"2024-09-06T13:34:08","modified_gmt":"2024-09-06T13:34:08","slug":"hilfe","status":"publish","type":"page","link":"https:\/\/topliefer.com\/en\/hilfe\/","title":{"rendered":"Help"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"25375\" class=\"elementor elementor-25375 elementor-21169\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3153d4b e-flex e-con-boxed e-con e-parent\" data-id=\"3153d4b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-63b684a e-con-full e-flex e-con e-child\" data-id=\"63b684a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e27cff6 elementor-widget elementor-widget-elementskit-heading\" data-id=\"e27cff6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h1 class=\"ekit-heading--title elementskit-section-title \">Got questions? Ask away.<\/h1>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Frequently asked questions, quick solutions, and official information about every feature - can't find your question here? Use our support form.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a54632 elementor-align-center elementor-widget elementor-widget-elementskit-button\" data-id=\"6a54632\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/topliefer.com\/en\/Hilfe-Center\/\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\t<i class=\"icon icon-Support-2\"><\/i>Support Form\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e7ca5f5 e-flex e-con-boxed e-con e-parent\" data-id=\"e7ca5f5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d68f093 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"d68f093\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4ac264f e-con-full e-flex e-con e-child\" data-id=\"4ac264f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2579150 e-con-full e-flex e-con e-child\" data-id=\"2579150\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-094b678 e-con-full sticky-section e-flex e-con e-child\" data-id=\"094b678\" data-element_type=\"container\" data-e-type=\"container\" id=\"section1\">\n\t\t<div class=\"elementor-element elementor-element-dce41be e-con-full e-flex e-con e-child\" data-id=\"dce41be\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d382e20 animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"d382e20\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h3 class=\"ekit-heading--title elementskit-section-title \">General Questions<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ab06f34 e-con-full e-flex e-con e-child\" data-id=\"ab06f34\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-808c81f animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-accordion\" data-id=\"808c81f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a04bd75e7056\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-808c81f\">\n                        <a href=\"#collapse-bc228306a04bd75e7056\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-bc228306a04bd75e7056\" aria-expanded=\"true\" aria-controls=\"Collapse-bc228306a04bd75e7056\">\n                            \n                            <span class=\"ekit-accordion-title\">Do you offer trial periods or demos?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-chevron-right\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-cross\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-bc228306a04bd75e7056\" class=\" show collapse\" aria-labelledby=\"primaryHeading-0-808c81f\" data-parent=\"#accordion-6a04bd75e7056\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>We offer demos so you can get a comprehensive view of how our technology can make your delivery processes more efficient. Although we do not offer a trial period for our plans, our customer service team is available to answer any questions to help you choose the right plan.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-808c81f\">\n                        <a href=\"#collapse-a0b77f06a04bd75e7056\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-a0b77f06a04bd75e7056\" aria-expanded=\"false\" aria-controls=\"Collapse-a0b77f06a04bd75e7056\">\n                            \n                            <span class=\"ekit-accordion-title\">Can I customize the design of the website or app, such as colors and layout, to match my branding?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-chevron-right\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-cross\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-a0b77f06a04bd75e7056\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-808c81f\" data-parent=\"#accordion-6a04bd75e7056\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Yes, we offer customization services to tailor the design of your website or app, including colors, layouts, and other visual elements, to align with your brand's identity. Please contact our support team for more details and to discuss your specific needs.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dd2881e e-con-full sticky-section e-flex e-con e-child\" data-id=\"dd2881e\" data-element_type=\"container\" data-e-type=\"container\" id=\"section2\">\n\t\t<div class=\"elementor-element elementor-element-08214aa e-con-full e-flex e-con e-child\" data-id=\"08214aa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fcc7ba5 elementor-widget elementor-widget-spacer\" data-id=\"fcc7ba5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77e36f0 animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"77e36f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h3 class=\"ekit-heading--title elementskit-section-title \">Pricing:<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-424ff59 e-con-full e-flex e-con e-child\" data-id=\"424ff59\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79502a9 animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-accordion\" data-id=\"79502a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a04bd75e8533\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-79502a9\">\n                        <a href=\"#collapse-bc228306a04bd75e8533\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-bc228306a04bd75e8533\" aria-expanded=\"true\" aria-controls=\"Collapse-bc228306a04bd75e8533\">\n                            \n                            <span class=\"ekit-accordion-title\">What types of plans does Top Liefer Technology offer?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-chevron-right\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-cross\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-bc228306a04bd75e8533\" class=\" show collapse\" aria-labelledby=\"primaryHeading-0-79502a9\" data-parent=\"#accordion-6a04bd75e8533\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"elementskit-card active\"><div class=\"elementskit-card-header\"><div class=\"ekit_accordion_icon_group\"><div class=\"ekit_accordion_active_icon\">We offer a range of plans tailored to suit the needs of individuals, small teams, and growing enterprises. Each plan is designed with your business goals in mind, ensuring you receive value regardless of your scale.<\/div><\/div><\/div><\/div><div class=\"elementskit-card\"><div class=\"elementskit-card-header\">\u00a0<\/div><\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-79502a9\">\n                        <a href=\"#collapse-393bb6f6a04bd75e8533\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-393bb6f6a04bd75e8533\" aria-expanded=\"false\" aria-controls=\"Collapse-393bb6f6a04bd75e8533\">\n                            \n                            <span class=\"ekit-accordion-title\">Are there any hidden fees associated with your pricing? <\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-chevron-right\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-cross\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-393bb6f6a04bd75e8533\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-79502a9\" data-parent=\"#accordion-6a04bd75e8533\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"collapse show\"><div class=\"elementskit-card-body ekit-accordion--content\"><p>Absolutely not! We believe in transparency, which means you\u2019ll only pay what you see. No hidden fees, no surprises.<\/p><\/div><\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-79502a9\">\n                        <a href=\"#collapse-cfbc1a76a04bd75e8533\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-cfbc1a76a04bd75e8533\" aria-expanded=\"false\" aria-controls=\"Collapse-cfbc1a76a04bd75e8533\">\n                            \n                            <span class=\"ekit-accordion-title\">Can I change my plan later?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-chevron-right\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-cross\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-cfbc1a76a04bd75e8533\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-79502a9\" data-parent=\"#accordion-6a04bd75e8533\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Yes, you can upgrade or downgrade your plan at any time. We understand that business needs change, and our flexible options are here to accommodate your growth.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-79502a9\">\n                        <a href=\"#collapse-9b275ad6a04bd75e8533\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-9b275ad6a04bd75e8533\" aria-expanded=\"false\" aria-controls=\"Collapse-9b275ad6a04bd75e8533\">\n                            \n                            <span class=\"ekit-accordion-title\">How can I find out which plan is best for my business?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-chevron-right\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-cross\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-9b275ad6a04bd75e8533\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-79502a9\" data-parent=\"#accordion-6a04bd75e8533\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"elementskit-card-header\">Our website features detailed information on each plan, including the features and benefits. If you need further assistance, our dedicated customer support team is just a message away, ready to help you make an informed decision.<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-79502a9\">\n                        <a href=\"#collapse-bb4825d6a04bd75e8533\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-bb4825d6a04bd75e8533\" aria-expanded=\"false\" aria-controls=\"Collapse-bb4825d6a04bd75e8533\">\n                            \n                            <span class=\"ekit-accordion-title\">What payment methods do you accept?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-chevron-right\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-cross\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-bb4825d6a04bd75e8533\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-79502a9\" data-parent=\"#accordion-6a04bd75e8533\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>We accept a variety of payment methods, including credit cards, bank transfers, and online payments, to make our services accessible to everyone.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d152ee e-con-full sticky-section e-flex e-con e-child\" data-id=\"4d152ee\" data-element_type=\"container\" data-e-type=\"container\" id=\"section3\">\n\t\t<div class=\"elementor-element elementor-element-22f7ec2 e-con-full e-flex e-con e-child\" data-id=\"22f7ec2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2862588 elementor-widget elementor-widget-spacer\" data-id=\"2862588\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8d65d8 animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"c8d65d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h3 class=\"ekit-heading--title elementskit-section-title \">Support &amp; updates:<\/h3>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>We offer different types of support, depending on your needs. Whether it's troubleshooting or design questions, we're here for you. With clear and easy-to-understand instructions, we make sure you get the support you need.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-10c6e7e e-con-full e-flex e-con e-child\" data-id=\"10c6e7e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e7ab6e7 animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-accordion\" data-id=\"e7ab6e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a04bd75e9bae\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-e7ab6e7\">\n                        <a href=\"#collapse-bc228306a04bd75e9bae\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-bc228306a04bd75e9bae\" aria-expanded=\"true\" aria-controls=\"Collapse-bc228306a04bd75e9bae\">\n                            \n                            <span class=\"ekit-accordion-title\">How can I report a problem with my website or application?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-chevron-right\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-cross\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-bc228306a04bd75e9bae\" class=\" show collapse\" aria-labelledby=\"primaryHeading-0-e7ab6e7\" data-parent=\"#accordion-6a04bd75e9bae\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Please use the<strong>\u00a0<a href=\"https:\/\/topliefer.com\/en\/hilfe-center\/\">Support form<\/a>\u00a0<\/strong>on our website to report any issues. Our team reviews all feedback and takes action to solve your issues.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Got questions? Ask away. Frequently asked questions, quick solutions, and official information about every feature &#8211; can&#8217;t find your question here? Use our support form. Support Form General Questions Do you offer trial periods or demos? We offer demos so you can get a comprehensive view of how our technology can make your delivery processes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-25375","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/topliefer.com\/en\/wp-json\/wp\/v2\/pages\/25375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/topliefer.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/topliefer.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/topliefer.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/topliefer.com\/en\/wp-json\/wp\/v2\/comments?post=25375"}],"version-history":[{"count":0,"href":"https:\/\/topliefer.com\/en\/wp-json\/wp\/v2\/pages\/25375\/revisions"}],"wp:attachment":[{"href":"https:\/\/topliefer.com\/en\/wp-json\/wp\/v2\/media?parent=25375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}